xf{"id":1023,"date":"2021-12-21T02:33:56","date_gmt":"2021-12-21T07:33:56","guid":{"rendered":"https:\/\/www.virlan.co\/trends\/?p=1023"},"modified":"2023-03-06T07:22:48","modified_gmt":"2023-03-06T12:22:48","slug":"johnny-depp-et-dune-au-festival-de-deauville-american-film-festival","status":"publish","type":"post","link":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/","title":{"rendered":"Johnny Depp et &#8220;Dune&#8221; au Festival de Deauville American Film Festival"},"content":{"rendered":"\n<h2 class=\"has-text-align-center wp-block-heading\">Festival de Deauville. Johnny Depp et Oliver Stone seront l\u00e0 pour la 47e \u00e9dition<\/h2>\n\n\n<p>Dans le tourmente \u00e0 Hollywood, <a href=\"https:\/\/www.virlan.co\/trends\/tag\/Johnny-Depp\/\">Johnny Depp<\/a> sera l\u2019invit\u00e9 d\u2019honneur du 47e Festival de Deauville, dont le jury sera pr\u00e9sid\u00e9 par Charlotte Gainsbourg. L\u2019acteur am\u00e9ricain pr\u00e9sentera &#8220;City of Lies&#8221; et participera \u00e0 une rencontre avec le public.<\/p>\n<p>C\u2019est LE gros coup des organisateurs du Festival de Deauville. Johnny Depp, 58 ans, fera le d\u00e9placement en Normandie pour la 47e \u00e9dition qui ouvrira ses portes le 3 septembre. L\u2019acteur am\u00e9ricain qui participera \u00e0 une rencontre avec le public, pr\u00e9sentera City of Lies, un thriller de Brad Furman consacr\u00e9 \u00e0 l\u2019enqu\u00eate sur la mort des rappeurs Notorious B.I.G. et Tupac Shakur. Le film, tourn\u00e9 en 2017, est longtemps rest\u00e9 in\u00e9dit en salles en raison des d\u00e9boires personnels de la star, accus\u00e9 de violences conjugales par son ex-\u00e9pouse, l\u2019actrice Amber Heard.<\/p>\n<p>En novembre dernier, le h\u00e9ros de Pirates des Cara\u00efbes a perdu son proc\u00e8s en diffamation contre le tablo\u00efd The Sun, qui l\u2019avait qualifi\u00e9 de &#8220;cogneur de femmes&#8221; dans un article de 2018. Le proc\u00e8s, qui s\u2019est d\u00e9roul\u00e9 \u00e0 Londres l\u2019\u00e9t\u00e9 dernier, a donn\u00e9 lieu \u00e0 un d\u00e9ballage sordide sur la vie du couple. Si Johnny Depp n\u2019a jamais \u00e9t\u00e9 reconnu coupable des faits qui lui sont reproch\u00e9s, sa &#8220;mauvaise r\u00e9putation&#8221; a entra\u00een\u00e9 son \u00e9viction du troisi\u00e8me volet de la franchise Les Animaux Fantastiques.<\/p>\n<p>\u00a0<\/p>\n<p>also read :<\/p>\n<p><a href=\"https:\/\/www.virlan.co\/trends\/amber-heard-johnny-depp-abuse-aclu-must-reveal-if-amber-heard-donated-7m-divorce-settlement\/\">amber heard johnny depp abuse : ACLU must reveal if Amber Heard donated $7M divorce settlement<\/a><\/p>\n<p>\u00a0<\/p>\n\n<h2 style=\"text-align: center;\">Festival de Deauville. Johnny Depp et Oliver Stone seront l\u00e0 pour la 47e \u00e9dition<\/h2>\n<p>\u200bLa conf\u00e9rence de presse de pr\u00e9sentation du Festival du cin\u00e9ma am\u00e9ricain de Deauville se tenait ce mardi 17 ao\u00fbt 2021 en fin de matin\u00e9e. L\u2019occasion, pour les organisateurs, d\u2019annoncer la venue d\u2019Am\u00e9ricains, pour cette 47e \u00e9dition qui se tiendra du 3 au 12 septembre, notamment Johnny Depp et Oliver Stone.<br \/>On en sait un peu plus sur la 47e \u00e9dition du Festival du cin\u00e9ma am\u00e9ricain de Deauville. Apr\u00e8s une \u00e9dition 2020 qui avait pu se maintenir malgr\u00e9 la crise sanitaire, et quelques jours apr\u00e8s avoir d\u00e9voil\u00e9 les premiers \u00e9l\u00e9ments de programmation de cette \u00e9dition 2021, les organisateurs ont annonc\u00e9, ce mardi 17 ao\u00fbt, la venue de deux noms qui vont parler au grand public.<\/p>\n<p>Entre le 3 et le 12 septembre, le festival deauvillais accueillera en personne l\u2019acteur Johnny Depp, qui viendra pour City of lies , de Brad Furman, et Oliver Stone, r\u00e9alisateur du documentaire JFK L\u2019Enqu\u00eate .<\/p>\n\n<p>also read :<\/p>\n<div id=\"block-d416217f-87c3-4de1-9c2c-35578844107d\" class=\"block-editor-block-list__block wp-block is-selected wp-block-rss\" tabindex=\"0\" role=\"group\" aria-label=\"Block: RSS\" data-block=\"d416217f-87c3-4de1-9c2c-35578844107d\" data-type=\"core\/rss\" data-title=\"RSS\">\n<div class=\"components-disabled css-idxg31-StyledWrapper e1ac3xxk0\">\n<div>\n<ul class=\"wp-block-rss\">\n<li class=\"wp-block-rss__item\">\n<div class=\"wp-block-rss__item-title\"><a tabindex=\"-1\" href=\"https:\/\/www.virlan.co\/trends\/metallicas-kirk-hammett\/\">Metallica\u2019s Kirk Hammett Reveals The Only Band That He And James Hetfield Love<\/a><\/div>\n<\/li>\n<li class=\"wp-block-rss__item\">\n<div class=\"wp-block-rss__item-title\"><a tabindex=\"-1\" href=\"https:\/\/www.virlan.co\/trends\/celebrity-car-insurance\/\">Great Car Insurance : \u201cThe Rock\u201d : Bugatti Chiron, Estimated At $2 Million! Exotic Car Insurance<\/a><\/div>\n<\/li>\n<li class=\"wp-block-rss__item\">\n<div class=\"wp-block-rss__item-title\"><a tabindex=\"-1\" href=\"https:\/\/www.virlan.co\/trends\/who-is-charli-damelio-tiktoks-biggest-star\/\">who is Charli D\u2019Amelio ? TikTok\u2019s biggest star<\/a><\/div>\n<\/li>\n<li class=\"wp-block-rss__item\">\n<div class=\"wp-block-rss__item-title\"><a tabindex=\"-1\" href=\"https:\/\/www.virlan.co\/trends\/kris-wu\/\">Kris Wu facing more date rape lawsuits \u2013 #MeToo movement<\/a><\/div>\n<\/li>\n<li class=\"wp-block-rss__item\">\n<div class=\"wp-block-rss__item-title\"><a tabindex=\"-1\" href=\"https:\/\/www.virlan.co\/trends\/most-popular-k-pop-bands\/\">The Most Popular K-pop bands : best boy &amp; girl groups<\/a><\/div>\n<\/li>\n<\/ul>\n<\/div>\n<\/div>\n<\/div>\n\n<p>\u00a0<\/p>\n<p>Johnny Depp sur les planches de Deauville. La star am\u00e9ricaine sera en Normandie le dimanche 5 septembre prochain pour une rencontre avec le public, en marge de la pr\u00e9sentation de \u00abCity of Lies\u00bb de Brad Furman. Apr\u00e8s avoir annonc\u00e9 les films en comp\u00e9titions, Bruno Barde a d\u00e9voil\u00e9 les membres des deux jurys du Festival. Celui de la comp\u00e9tition autour de Charlotte Gainsbourg sera compos\u00e9 Bertrand Bonello, Delphine de Vigan, Mikha\u00ebl Hers, Garance Marillier, Fatou N&#8217;Diaye, Denis Podalyd\u00e8s, Marcia Romano et SebastiAn. Le jury de la R\u00e9v\u00e9lation sera lui compos\u00e9 de Cl\u00e9mence Po\u00e9sy (pr\u00e9sidente), C\u00e9leste Brunnquell, India Hair, Lomepal et Kacey Mottet Klein.<\/p>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"has-text-align-center has-accent-background-color has-background wp-block-heading\">Deauville American Film Festival<\/h2>\n\n\n<p>The Deauville American Film Festival (French: Festival du cin\u00e9ma am\u00e9ricain de Deauville) is a yearly film festival devoted to American cinema, taking place since 1975 in Deauville, France.[1][2]<\/p>\n<p>It was established by Lionel Chouchan, Andr\u00e9 Halimi, and then Mayor of Deauville Michel d&#8217;Ornano, with support from the Groupe Lucien Barri\u00e8re in providing a luxurious setting for the Festival.[3] Although not competitive at its origin, the festival began to award prizes for feature films in 1995 and short films in 1998.<\/p>","protected":false},"excerpt":{"rendered":"<p>Festival de Deauville. Johnny Depp et Oliver Stone seront l\u00e0 pour la 47e \u00e9dition Dans le tourmente \u00e0 Hollywood, Johnny Depp sera l\u2019invit\u00e9 d\u2019honneur du 47e Festival de Deauville, dont le jury sera pr\u00e9sid\u00e9 par Charlotte Gainsbourg. L\u2019acteur am\u00e9ricain pr\u00e9sentera &#8220;City of Lies&#8221; et participera \u00e0 une rencontre avec le public. C\u2019est LE gros coup [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[597,990],"tags":[5684,5685,5686,2955],"class_list":["post-1023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-celebrity","category-trending","tag-australia","tag-canada","tag-united-kingdom","tag-united-states"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Johnny Depp et &quot;Dune&quot; au Festival de Deauville American Film Festival<\/title>\n<meta name=\"description\" content=\"Festival de Deauville. Johnny Depp et Oliver Stone seront l\u00e0 pour la 47e \u00e9dition. Johnny Depp sera bien sur les planches de Deauville d\u00e9but septembre\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Johnny Depp et &quot;Dune&quot; au Festival de Deauville American Film Festival\" \/>\n<meta property=\"og:description\" content=\"Festival de Deauville. Johnny Depp et Oliver Stone seront l\u00e0 pour la 47e \u00e9dition. Johnny Depp sera bien sur les planches de Deauville d\u00e9but septembre\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/\" \/>\n<meta property=\"og:site_name\" content=\"VIRLAN Trends\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-21T07:33:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-06T12:22:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.virlan.co\/trends\/wp-content\/uploads\/2021\/08\/Johnny-Depp-et-Dune-au-Festival-de-Deauville-.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Bill\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@virlanco\" \/>\n<meta name=\"twitter:site\" content=\"@virlanco\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Bill\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/\"},\"author\":{\"name\":\"Bill\",\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/#\\\/schema\\\/person\\\/cc915fd6d087646807d5eebef323a56c\"},\"headline\":\"Johnny Depp et &#8220;Dune&#8221; au Festival de Deauville American Film Festival\",\"datePublished\":\"2021-12-21T07:33:56+00:00\",\"dateModified\":\"2023-03-06T12:22:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/\"},\"wordCount\":708,\"publisher\":{\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Johnny-Depp-et-Dune-au-Festival-de-Deauville-.jpg\",\"keywords\":[\"Australia\",\"Canada\",\"United Kingdom\",\"United States\"],\"articleSection\":[\"Celebrity\",\"trending\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/\",\"url\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/\",\"name\":\"Johnny Depp et \\\"Dune\\\" au Festival de Deauville American Film Festival\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Johnny-Depp-et-Dune-au-Festival-de-Deauville-.jpg\",\"datePublished\":\"2021-12-21T07:33:56+00:00\",\"dateModified\":\"2023-03-06T12:22:48+00:00\",\"description\":\"Festival de Deauville. Johnny Depp et Oliver Stone seront l\u00e0 pour la 47e \u00e9dition. Johnny Depp sera bien sur les planches de Deauville d\u00e9but septembre\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Johnny-Depp-et-Dune-au-Festival-de-Deauville-.jpg\",\"contentUrl\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Johnny-Depp-et-Dune-au-Festival-de-Deauville-.jpg\",\"width\":700,\"height\":466,\"caption\":\"Johnny Depp et \\\"Dune\\\" au Festival de Deauville\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/trending\\\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Johnny Depp et &#8220;Dune&#8221; au Festival de Deauville American Film Festival\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/#website\",\"url\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/\",\"name\":\"VIRLAN\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/#organization\",\"name\":\"VIRLAN\",\"url\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/VIRLAN-1-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/wp-content\\\/uploads\\\/2021\\\/12\\\/VIRLAN-1-1.jpg\",\"width\":141,\"height\":50,\"caption\":\"VIRLAN\"},\"image\":{\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/virlanco\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.virlan.co\\\/trends\\\/#\\\/schema\\\/person\\\/cc915fd6d087646807d5eebef323a56c\",\"name\":\"Bill\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16e28c7e3cd4aab15415d0efef86d06f0e09515d52d4ee24c43a9ef706e44c12?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16e28c7e3cd4aab15415d0efef86d06f0e09515d52d4ee24c43a9ef706e44c12?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/16e28c7e3cd4aab15415d0efef86d06f0e09515d52d4ee24c43a9ef706e44c12?s=96&d=mm&r=g\",\"caption\":\"Bill\"},\"description\":\"Trending News\",\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/in\\\/abbas-falsafin\\\/\",\"https:\\\/\\\/x.com\\\/virlanco\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Johnny Depp et \"Dune\" au Festival de Deauville American Film Festival","description":"Festival de Deauville. Johnny Depp et Oliver Stone seront l\u00e0 pour la 47e \u00e9dition. Johnny Depp sera bien sur les planches de Deauville d\u00e9but septembre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/","og_locale":"en_US","og_type":"article","og_title":"Johnny Depp et \"Dune\" au Festival de Deauville American Film Festival","og_description":"Festival de Deauville. Johnny Depp et Oliver Stone seront l\u00e0 pour la 47e \u00e9dition. Johnny Depp sera bien sur les planches de Deauville d\u00e9but septembre","og_url":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/","og_site_name":"VIRLAN Trends","article_published_time":"2021-12-21T07:33:56+00:00","article_modified_time":"2023-03-06T12:22:48+00:00","og_image":[{"width":700,"height":466,"url":"https:\/\/www.virlan.co\/trends\/wp-content\/uploads\/2021\/08\/Johnny-Depp-et-Dune-au-Festival-de-Deauville-.jpg","type":"image\/jpeg"}],"author":"Bill","twitter_card":"summary_large_image","twitter_creator":"@virlanco","twitter_site":"@virlanco","twitter_misc":{"Written by":"Bill","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/#article","isPartOf":{"@id":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/"},"author":{"name":"Bill","@id":"https:\/\/www.virlan.co\/trends\/#\/schema\/person\/cc915fd6d087646807d5eebef323a56c"},"headline":"Johnny Depp et &#8220;Dune&#8221; au Festival de Deauville American Film Festival","datePublished":"2021-12-21T07:33:56+00:00","dateModified":"2023-03-06T12:22:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/"},"wordCount":708,"publisher":{"@id":"https:\/\/www.virlan.co\/trends\/#organization"},"image":{"@id":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/#primaryimage"},"thumbnailUrl":"https:\/\/www.virlan.co\/trends\/wp-content\/uploads\/2021\/08\/Johnny-Depp-et-Dune-au-Festival-de-Deauville-.jpg","keywords":["Australia","Canada","United Kingdom","United States"],"articleSection":["Celebrity","trending"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/","url":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/","name":"Johnny Depp et \"Dune\" au Festival de Deauville American Film Festival","isPartOf":{"@id":"https:\/\/www.virlan.co\/trends\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/#primaryimage"},"image":{"@id":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/#primaryimage"},"thumbnailUrl":"https:\/\/www.virlan.co\/trends\/wp-content\/uploads\/2021\/08\/Johnny-Depp-et-Dune-au-Festival-de-Deauville-.jpg","datePublished":"2021-12-21T07:33:56+00:00","dateModified":"2023-03-06T12:22:48+00:00","description":"Festival de Deauville. Johnny Depp et Oliver Stone seront l\u00e0 pour la 47e \u00e9dition. Johnny Depp sera bien sur les planches de Deauville d\u00e9but septembre","breadcrumb":{"@id":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/#primaryimage","url":"https:\/\/www.virlan.co\/trends\/wp-content\/uploads\/2021\/08\/Johnny-Depp-et-Dune-au-Festival-de-Deauville-.jpg","contentUrl":"https:\/\/www.virlan.co\/trends\/wp-content\/uploads\/2021\/08\/Johnny-Depp-et-Dune-au-Festival-de-Deauville-.jpg","width":700,"height":466,"caption":"Johnny Depp et \"Dune\" au Festival de Deauville"},{"@type":"BreadcrumbList","@id":"https:\/\/www.virlan.co\/trends\/trending\/johnny-depp-et-dune-au-festival-de-deauville-american-film-festival\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.virlan.co\/trends\/"},{"@type":"ListItem","position":2,"name":"Johnny Depp et &#8220;Dune&#8221; au Festival de Deauville American Film Festival"}]},{"@type":"WebSite","@id":"https:\/\/www.virlan.co\/trends\/#website","url":"https:\/\/www.virlan.co\/trends\/","name":"VIRLAN","description":"","publisher":{"@id":"https:\/\/www.virlan.co\/trends\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.virlan.co\/trends\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.virlan.co\/trends\/#organization","name":"VIRLAN","url":"https:\/\/www.virlan.co\/trends\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.virlan.co\/trends\/#\/schema\/logo\/image\/","url":"https:\/\/www.virlan.co\/trends\/wp-content\/uploads\/2021\/12\/VIRLAN-1-1.jpg","contentUrl":"https:\/\/www.virlan.co\/trends\/wp-content\/uploads\/2021\/12\/VIRLAN-1-1.jpg","width":141,"height":50,"caption":"VIRLAN"},"image":{"@id":"https:\/\/www.virlan.co\/trends\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/virlanco"]},{"@type":"Person","@id":"https:\/\/www.virlan.co\/trends\/#\/schema\/person\/cc915fd6d087646807d5eebef323a56c","name":"Bill","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/16e28c7e3cd4aab15415d0efef86d06f0e09515d52d4ee24c43a9ef706e44c12?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/16e28c7e3cd4aab15415d0efef86d06f0e09515d52d4ee24c43a9ef706e44c12?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/16e28c7e3cd4aab15415d0efef86d06f0e09515d52d4ee24c43a9ef706e44c12?s=96&d=mm&r=g","caption":"Bill"},"description":"Trending News","sameAs":["https:\/\/www.linkedin.com\/in\/abbas-falsafin\/","https:\/\/x.com\/virlanco"]}]}},"_links":{"self":[{"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/posts\/1023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/comments?post=1023"}],"version-history":[{"count":2,"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/posts\/1023\/revisions"}],"predecessor-version":[{"id":1026,"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/posts\/1023\/revisions\/1026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/media\/1024"}],"wp:attachment":[{"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/media?parent=1023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/categories?post=1023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.virlan.co\/trends\/wp-json\/wp\/v2\/tags?post=1023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}